{"id":174739,"date":"2022-03-27T22:37:49","date_gmt":"2022-03-27T22:37:49","guid":{"rendered":"https:\/\/www.golf1.is\/wp-content\/uploads\/2022\/03\/Scottie-Scheffler-Bag.png.webp"},"modified":"2022-03-27T22:38:06","modified_gmt":"2022-03-27T22:38:06","slug":"scottie-scheffler-bag-png-2","status":"inherit","type":"attachment","link":"https:\/\/www.golf1.is\/en\/scottie-scheffler-bag-png-2\/","title":{"rendered":"Scottie-Scheffler-Bag.png"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_links_to":"","_links_to_target":""},"class_list":["post-174739","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.golf1.is\/wp-content\/uploads\/2022\/03\/Scottie-Scheffler-Bag.png.webp'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"128\" src=\"https:\/\/www.golf1.is\/wp-content\/uploads\/2022\/03\/Scottie-Scheffler-Bag.png-300x128.webp\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.golf1.is\/wp-content\/uploads\/2022\/03\/Scottie-Scheffler-Bag.png-300x128.webp 300w, https:\/\/www.golf1.is\/wp-content\/uploads\/2022\/03\/Scottie-Scheffler-Bag.png.webp 620w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/webp","media_details":{"width":620,"height":264,"file":"2022\/03\/Scottie-Scheffler-Bag.png.webp","sizes":{"medium":{"file":"Scottie-Scheffler-Bag.png-300x128.webp","width":300,"height":128,"mime_type":"image\/webp","source_url":"https:\/\/www.golf1.is\/wp-content\/uploads\/2022\/03\/Scottie-Scheffler-Bag.png-300x128.webp"},"thumbnail":{"file":"Scottie-Scheffler-Bag.png-150x150.webp","width":150,"height":150,"mime_type":"image\/webp","source_url":"https:\/\/www.golf1.is\/wp-content\/uploads\/2022\/03\/Scottie-Scheffler-Bag.png-150x150.webp"},"top3":{"file":"Scottie-Scheffler-Bag.png-129x73.webp","width":129,"height":73,"mime_type":"image\/webp","source_url":"https:\/\/www.golf1.is\/wp-content\/uploads\/2022\/03\/Scottie-Scheffler-Bag.png-129x73.webp"},"top7":{"file":"Scottie-Scheffler-Bag.png-98x56.webp","width":98,"height":56,"mime_type":"image\/webp","source_url":"https:\/\/www.golf1.is\/wp-content\/uploads\/2022\/03\/Scottie-Scheffler-Bag.png-98x56.webp"},"ad_top":{"file":"Scottie-Scheffler-Bag.png-175x150.webp","width":175,"height":150,"mime_type":"image\/webp","source_url":"https:\/\/www.golf1.is\/wp-content\/uploads\/2022\/03\/Scottie-Scheffler-Bag.png-175x150.webp"},"ad_center":{"file":"Scottie-Scheffler-Bag.png-620x150.webp","width":620,"height":150,"mime_type":"image\/webp","source_url":"https:\/\/www.golf1.is\/wp-content\/uploads\/2022\/03\/Scottie-Scheffler-Bag.png-620x150.webp"},"ad_bottom":{"file":"Scottie-Scheffler-Bag.png-170x264.webp","width":170,"height":264,"mime_type":"image\/webp","source_url":"https:\/\/www.golf1.is\/wp-content\/uploads\/2022\/03\/Scottie-Scheffler-Bag.png-170x264.webp"},"ad_sidebar":{"file":"Scottie-Scheffler-Bag.png-270x180.webp","width":270,"height":180,"mime_type":"image\/webp","source_url":"https:\/\/www.golf1.is\/wp-content\/uploads\/2022\/03\/Scottie-Scheffler-Bag.png-270x180.webp"},"detail":{"file":"Scottie-Scheffler-Bag.png-160x90.webp","width":160,"height":90,"mime_type":"image\/webp","source_url":"https:\/\/www.golf1.is\/wp-content\/uploads\/2022\/03\/Scottie-Scheffler-Bag.png-160x90.webp"},"full":{"file":"Scottie-Scheffler-Bag.png.webp","width":620,"height":264,"mime_type":"image\/webp","source_url":"https:\/\/www.golf1.is\/wp-content\/uploads\/2022\/03\/Scottie-Scheffler-Bag.png.webp"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.golf1.is\/wp-content\/uploads\/2022\/03\/Scottie-Scheffler-Bag.png.webp","_links":{"self":[{"href":"https:\/\/www.golf1.is\/en\/wp-json\/wp\/v2\/media\/174739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.golf1.is\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.golf1.is\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.golf1.is\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.golf1.is\/en\/wp-json\/wp\/v2\/comments?post=174739"}]}}